{"id":970,"date":"2024-01-04T17:11:51","date_gmt":"2024-01-04T16:11:51","guid":{"rendered":"https:\/\/travelerandexplorergirl.com\/?p=970"},"modified":"2024-10-25T21:46:20","modified_gmt":"2024-10-25T19:46:20","slug":"como-conducir-en-francia-permiso-extranjero-o-licencia-francesa","status":"publish","type":"post","link":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/","title":{"rendered":"\u00bfC\u00f3mo conducir en Francia: permiso extranjero o licencia francesa?"},"content":{"rendered":"\n<h2 align=\"center\">\nUna de las preguntas m\u00e1s frecuentes cuando venimos a estudiar o a trabajar en Francia y si tenemos una licencia de conducir de nuestro pa\u00eds natal, es si es posible conducir en Francia con nuestro permiso ya adquirido.  <\/h2>\n<h2 align=\"center\">De cierta manera depende de cada situaci\u00f3n, lo esencial es saber que dependiendo de tu pa\u00eds, es posible o no.<\/h2>\n\n\n\n<h3><strong>1. Conducir en Francia si vienes temporalmente<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando llegu\u00e9 aqui como asistente de espa\u00f1ol y sab\u00eda que me iba a quedar \u00fanicamente 8 meses aqu\u00ed, no me preocup\u00e9 por<strong> conducir<\/strong>. GRAVE ERROR. Grave error en el sentido en que como estudiante, o con una visa de asalariado de corta duraci\u00f3n, podemos conducir en Francia con nuestro <strong>permiso de conducir extranjero <\/strong>(traducido, claro est\u00e1, por un <strong>traductor jurado<\/strong>) durante <strong>un a\u00f1o<\/strong> sin problema alguno. S\u00f3lo es necesario presentar el original y su traducci\u00f3n en caso de un control de la polic\u00eda francesa.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si necesitas un traductor jurado aqu\u00ed en Francia, te comparto <strong>la lista de traductores oficiales del consulado de Colombia en Francia<\/strong>. Si est\u00e1s en tu pa\u00eds de origen, te invito a consultar la p\u00e1gina web del consulado franc\u00e9s de tu pa\u00eds, all\u00ed encontrar\u00e1s una<strong><a href=\"https:\/\/www.courdecassation.fr\/experts-agrees-par-les-cours-dappel?utm_source=travelerandexplorergirl\"> lista de traductores jurados<\/a>.<\/strong><\/p>\n\n\n\n<h3><strong>2.<\/strong> <strong>Conducir en Francia si quieres instalarte en el pa\u00eds.<\/strong><\/h3>\n\n\n<p><!-- \/wp:post-content --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Si deseas <strong>instalarte en Francia<\/strong>, te aconsejo utilizar tu<strong> permiso de conducir<\/strong> traducido durante <strong>el primer a\u00f1o<\/strong>. Desafortunadamente, seg\u00fan tu pa\u00eds de origen, no podr\u00e1s utilizarlo m\u00e1s despu\u00e9s de tu primer a\u00f1o de llegada a Francia. Si est\u00e1s en ese caso, tienes dos opciones: <strong>cambiar tu permiso de conducir <\/strong>de origen\u00a0 por uno franc\u00e9s (\u00fanicamente si los dos pa\u00edses hicieron el acuerdo) o debes <a href=\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/obten-licencia-conduccion-francia\/\"><strong>pasar el permiso de conducir franc\u00e9s<\/strong><\/a> desde cero.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Si quieres saber si tu pa\u00eds tiene convenio con Francia para cambiar el permiso de conducir, <a href=\"https:\/\/www.diplomatie.gouv.fr\/IMG\/pdf\/---_liste_permis_de_conduire_valables_a_l_echange_09.12.2021---_cle8735a7.pdf?utm_source=travelerandexplorergirl\">consulta aqu\u00ed<\/a> la lista de pa\u00edses autorizados. Tambi\u00e9n podr\u00e1s encontrar m\u00e1s informaci\u00f3n sobre los dos procedimientos en la p\u00e1gina <a href=\"https:\/\/permisdeconduire.ants.gouv.fr\/?utm_source=travelerandexplorergirl\"><strong>ANTS- Permis de conduire<\/strong><\/a>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:html --><\/p>\n<h3><strong> a. Cambiar tu permiso de conducir de tu pa\u00eds natal por el permiso de conducir franc\u00e9s.<\/strong><\/h3>\n<p>Despu\u00e9s del primer a\u00f1o de utilizaci\u00f3n de tu permiso y si tu pa\u00eds tiene convenio con Francia, podr\u00e1s hacer una equivalencia de tu permiso y as\u00ed poder conducir en Francia. Si deseas m\u00e1s informaci\u00f3n sobre este procedimiento, te invito a visitar <a href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F1460?utm_source=travelerandexplorergirl\"> la p\u00e1gina de los servicios p\u00fablicos de Francia. <\/a><\/p>\n<h3><strong>b. Sacar tu permiso de conducir franc\u00e9s. <\/strong><\/h3>\n<p>Me concentro m\u00e1s en esta opci\u00f3n porque s\u00e9 que es la m\u00e1s presente para nosotros los latinoamericanos. Debes saber que en Francia, existen dos maneras de pasar <strong>el permiso de conducir<\/strong>: como <strong>candidato libre<\/strong> o como <strong>candidato de una escuela de conducci\u00f3n<\/strong>.<\/p>\n<p><!-- \/wp:html --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>La diferencia reside en que la<strong> escuela de conducci\u00f3n<\/strong> va a ocuparse de todas las cuestiones administrativas como la obtenci\u00f3n de tu n\u00famero <strong>NEPH<\/strong> (para identificarte como candidato), al <strong>examen te\u00f3rico<\/strong> y el <strong>examen pr\u00e1ctico<\/strong>, para producir tu tarjeta de <strong>permiso de conducir<\/strong> una vez hayas logrado el examen pr\u00e1ctico, entre otras. Adem\u00e1s, gracias a la escuela, podr\u00e1s <strong>preparar tus ex\u00e1menes <\/strong>con sus materiales, instructores y consejos (puedes aprender o <strong>practicar conducci\u00f3n <\/strong>durante<strong> 20 horas <\/strong>acompa\u00f1ada por un<strong> instructor certificado<\/strong>).<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Mientras que como <strong>candidato libre <\/strong>tu deber\u00e1s encargarte de todo esto y hacerlo t\u00fa mismo. La ventaja de que la escuela se encargue de todo esto tiene un precio. Y este precio depende del tipo de escuela que elijas: <strong>presencial<\/strong> o<strong> en l\u00ednea.<\/strong> En cualquiera de los dos casos, debes presentar primero <strong>el examen de c\u00f3digo de la ruta franc\u00e9s<\/strong>, cuyo costo es de 30\u20ac y luego <strong>el examen pr\u00e1ctico <\/strong>que te avala para conducir en Francia.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Espero que mi art\u00edculo te haya sido \u00fatil y que ahora sepas si puedes <strong>conducir o no en Francia<\/strong> con tu <strong>permiso extranjero<\/strong>. Toda la informaci\u00f3n que te he compartido ha sido tomada de la p\u00e1gina oficial de <strong>\u00abService Public\u00bb<\/strong> de Francia. Si quieres conocer m\u00e1s el <strong>procedimiento para obtener el permiso de conducir franc\u00e9s o cambiar tu licencia de conducir extranjera por una francesa<\/strong>, no dudes en decirmelo por mis redes sociales y escribir\u00e9 un art\u00edculo sobre esto una pr\u00f3xima vez.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Muchas gracias por leerme y ser parte de mi comunidad. Hasta pronto.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Traveler and explorer girl<\/p>\n<p><strong>iSuscr\u00edbete a mi newsletter!<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Si quieres estar al tanto de mis \u00faltimas publicaciones, no dudes en inscribirte aqu\u00ed.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:quote --><\/p>\n<blockquote class=\"wp-block-quote\">\n<p><!-- wp:html --><br \/>\n\t\t\t\t\t\t<script data-jetpack-boost=\"ignore\">\n\t\t\t\t\t\t\twindow.hsFormsOnReady = window.hsFormsOnReady || [];\n\t\t\t\t\t\t\twindow.hsFormsOnReady.push(()=>{\n\t\t\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\t\t\tportalId: 26994475,\n\t\t\t\t\t\t\t\t\tformId: \"52fc3b80-b6fb-48cf-ab9c-09f3de2951bf\",\n\t\t\t\t\t\t\t\t\ttarget: \"#hbspt-form-1784152153000-1373191438\",\n\t\t\t\t\t\t\t\t\tregion: \"eu1\",\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t})});\n\t\t\t\t\t\t<\/script>\n\t\t\t\t\t\t<div class=\"hbspt-form\" id=\"hbspt-form-1784152153000-1373191438\"><\/div><br \/><!-- \/wp:html --><\/p>\n<\/blockquote>\n<p><!-- \/wp:quote --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><em>Art\u00edculo escrito por Paola Moreno, el 4 de enero de 2024.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfConducir en Francia es posible cuando se tiene una licencia extranjera? <\/p>\n","protected":false},"author":2,"featured_media":992,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,2],"tags":[49,16,19,23,34],"class_list":["post-970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-migracion","category-vida-en-francia","tag-europa","tag-francia","tag-instalarse-en-francia","tag-migrar-a-francia","tag-vivir-en-francia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa<\/title>\n<meta name=\"description\" content=\"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa\" \/>\n<meta property=\"og:description\" content=\"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Traveler and Explorer Girl\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-04T16:11:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T19:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paola Moreno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paola Moreno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/\",\"url\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/\",\"name\":\"C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa\",\"isPartOf\":{\"@id\":\"https:\/\/travelerandexplorergirl.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2024-01-04T16:11:51+00:00\",\"dateModified\":\"2024-10-25T19:46:20+00:00\",\"author\":{\"@id\":\"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/69b26fe20b3fb0c81cce5b6e5f3fda25\"},\"description\":\"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707,\"caption\":\"licencia-extranjera-obtenerlicenciaconduccionfrancia-travelerandexplorergirl-vivirenfrancia-conducirenfrancia-permisodeconducir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/travelerandexplorergirl.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo conducir en Francia: permiso extranjero o licencia francesa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/#website\",\"url\":\"https:\/\/travelerandexplorergirl.com\/\",\"name\":\"Traveler and Explorer Girl\",\"description\":\"Migraci\u00f3n a Francia, viajes y consejos de una latina en Francia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/travelerandexplorergirl.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/69b26fe20b3fb0c81cce5b6e5f3fda25\",\"name\":\"Paola Moreno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1291c331b1b27eae407c612ecffaa45d2b9fd5aac44fcc40fe3d4d3de60f0f64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1291c331b1b27eae407c612ecffaa45d2b9fd5aac44fcc40fe3d4d3de60f0f64?s=96&d=mm&r=g\",\"caption\":\"Paola Moreno\"},\"url\":\"https:\/\/travelerandexplorergirl.com\/index.php\/author\/gipamoga\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa","description":"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa","og_description":"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.","og_url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/","og_site_name":"Traveler and Explorer Girl","article_published_time":"2024-01-04T16:11:51+00:00","article_modified_time":"2024-10-25T19:46:20+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1-1024x683.png","type":"image\/png"}],"author":"Paola Moreno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Paola Moreno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/","url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/","name":"C\u00f3mo conducir en Francia: permiso extranjero o licencia francesa","isPartOf":{"@id":"https:\/\/travelerandexplorergirl.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage"},"image":{"@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1","datePublished":"2024-01-04T16:11:51+00:00","dateModified":"2024-10-25T19:46:20+00:00","author":{"@id":"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/69b26fe20b3fb0c81cce5b6e5f3fda25"},"description":"Inf\u00f3rmate si puedes conducir coche en Francia con tu licencia extranjera o si necesitas un permiso de conducir franc\u00e9s.","breadcrumb":{"@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#primaryimage","url":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1","width":2560,"height":1707,"caption":"licencia-extranjera-obtenerlicenciaconduccionfrancia-travelerandexplorergirl-vivirenfrancia-conducirenfrancia-permisodeconducir"},{"@type":"BreadcrumbList","@id":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/como-conducir-en-francia-permiso-extranjero-o-licencia-francesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/travelerandexplorergirl.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo conducir en Francia: permiso extranjero o licencia francesa?"}]},{"@type":"WebSite","@id":"https:\/\/travelerandexplorergirl.com\/#website","url":"https:\/\/travelerandexplorergirl.com\/","name":"Traveler and Explorer Girl","description":"Migraci\u00f3n a Francia, viajes y consejos de una latina en Francia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelerandexplorergirl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/69b26fe20b3fb0c81cce5b6e5f3fda25","name":"Paola Moreno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelerandexplorergirl.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1291c331b1b27eae407c612ecffaa45d2b9fd5aac44fcc40fe3d4d3de60f0f64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1291c331b1b27eae407c612ecffaa45d2b9fd5aac44fcc40fe3d4d3de60f0f64?s=96&d=mm&r=g","caption":"Paola Moreno"},"url":"https:\/\/travelerandexplorergirl.com\/index.php\/author\/gipamoga\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2024\/01\/conducir-francia-permisodeconducir-licenciadeconducir-latinos-travelerandexplorergirl-GPMGDigital-1-1.png?fit=2560%2C1707&ssl=1","jetpack-related-posts":[{"id":1183,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/obtener-licencia-conducir-francesa\/","url_meta":{"origin":970,"position":0},"title":"Obt\u00e9n tu licencia de conducir francesa.","author":"Paola Moreno","date":"23 abril 2024","format":false,"excerpt":"Como obtener el permiso de conducir en Francia, siendo migrante extraeuropeo: procedimiento y documentos necesarios.","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":226,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/vida-en-francia\/navidad-en-francia\/","url_meta":{"origin":970,"position":1},"title":"Navidad en Francia","author":"Paola","date":"25 diciembre 2019","format":false,"excerpt":"Gracias a este art\u00edculo quiero compartirles mi experiencia personal de Navidad en Francia como migrante latinoam\u00e9ricana. Hace ya once a\u00f1os que vivo en Francia y pasar estas fiestas lejos de casa, de mi tierra natal y de mi familia, no es para nada f\u00e1cil. Los a\u00f1os anteriores hab\u00edan sido para\u2026","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/2019\/12\/whatsapp-image-2019-12-25-at-19.50.07.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":480,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/ninera-una-oportunidad-de-trabajo-en-francia\/","url_meta":{"origin":970,"position":2},"title":"Una oportunidad de trabajo en Francia: Cuidar ni\u00f1os.","author":"Paola Moreno","date":"26 marzo 2023","format":false,"excerpt":"Ser ninera en Francia: otra posibilidad de trabajo en este pais.","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia-travelerandexplorergirl","src":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/ninera-nounou-babysitting-trabajoenfrancia-francia-migrarafrancia.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":248,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/consejos-antes-de-venir-a-estudiar-o-vivir-en-francia\/","url_meta":{"origin":970,"position":3},"title":"Consejos antes de venir a estudiar o vivir en Francia.","author":"Paola","date":"16 febrero 2021","format":false,"excerpt":"Seg\u00fan mi experiencia, luego de tomar la decisi\u00f3n de trabajar o estudiar en Francia es important\u00edsimo preparar el proceso de migraci\u00f3n. Por eso quiero ofrecerte estos consejos para vivir en Francia: Aprender lo b\u00e1sico del idioma franc\u00e9s. Muchos colombianos menosprecian este aspecto tan relevante. Llegar a Francia hablando franc\u00e9s, aunque\u2026","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"estudiarenfrancia-travelerandexplorergirl-Sorbona-migrarafrancia-consejosparavivirenFrancia","src":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2021\/02\/estudiarenfrancia.jpg?fit=835%2C626&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2021\/02\/estudiarenfrancia.jpg?fit=835%2C626&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2021\/02\/estudiarenfrancia.jpg?fit=835%2C626&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2021\/02\/estudiarenfrancia.jpg?fit=835%2C626&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":288,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/migracion\/claves-para-trabajar-en-francia\/","url_meta":{"origin":970,"position":4},"title":"Trabajar en Francia: Algunos consejos para instalarte aqu\u00ed.","author":"Paola","date":"23 noviembre 2022","format":false,"excerpt":"Una vez llegado(a) a Francia adem\u00e1s de encontrar un alojamiento, abrir una cuenta bancaria, inscribirse a la seguridad social, comprar una tarjeta telef\u00f3nica para tu celular y obtener la vi\u00f1eta de la OFII; encontrar un trabajo es esencial para la estabilidad econ\u00f3mica. Primer requisito para trabajar en Francia: Visa o\u2026","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"logofrancetravail-travelerandexplorergirl","src":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2022\/11\/logofrancetravail.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2022\/11\/logofrancetravail.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2022\/11\/logofrancetravail.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2022\/11\/logofrancetravail.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2022\/11\/logofrancetravail.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":445,"url":"https:\/\/travelerandexplorergirl.com\/index.php\/vida-en-francia\/abre-tu-cuenta-bancaria-sin-comisiones-en-francia\/","url_meta":{"origin":970,"position":5},"title":"Abrir una cuenta bancaria en Francia gratis","author":"Paola","date":"3 marzo 2023","format":false,"excerpt":"UNA DE LAS GRANDES DIFERENCIAS EN T\u00c9RMINOS DE DINERO ENTRE LATINOAM\u00c9RICA Y FRANCIA ES QUE EN ESTE PAIS EUROPEO EL USO DE EFECTIVO ES CASI INEXISTENTE. EN CAMBIO, EL USO DE TARJETA CR\u00c9DITO O D\u00c9BITO SE CONVIRTIO EN EL PAN DE CADA DIA. Por esta raz\u00f3n uno de los pasos\u2026","rel":"","context":"En \u00abMigraci\u00f3n-Migration\u00bb","block_context":{"text":"Migraci\u00f3n-Migration","link":"https:\/\/travelerandexplorergirl.com\/index.php\/categoria\/migracion\/"},"img":{"alt_text":"cuentabancaria-gratis-francia-boursorama-tarjetabancaria-","src":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/travelerandexplorergirl.com\/wp-content\/uploads\/2023\/03\/cartebancaire-tarjetacredito-cuentabancaria-comptebancaire.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":41,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"predecessor-version":[{"id":1454,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions\/1454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/media\/992"}],"wp:attachment":[{"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelerandexplorergirl.com\/index.php\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}